{"id":10,"count":3,"description":"Eventos de encuentro de novios","link":"https:\/\/ecnovios.org\/ver\/categoria\/eventos\/","name":"Eventos","slug":"eventos","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/ecnovios.org\/ver\/wp-json\/wp\/v2\/categories\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecnovios.org\/ver\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/ecnovios.org\/ver\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/ecnovios.org\/ver\/wp-json\/wp\/v2\/posts?categories=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}